{"id":954,"date":"2012-05-23T09:32:52","date_gmt":"2012-05-23T09:32:52","guid":{"rendered":"https:\/\/intermediaproducciones.com\/?p=954"},"modified":"2012-05-23T09:52:17","modified_gmt":"2012-05-23T09:52:17","slug":"el-cortometraje-atados-de-paco-almazo-completo-en-vimeo","status":"publish","type":"post","link":"https:\/\/intermediaproducciones.com\/en\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/","title":{"rendered":"El cortometraje \u00abAtados\u00bb, de Paco Almazo, completo en vimeo"},"content":{"rendered":"<div><\/div>\n<div><\/div>\n<div>Hemos subido a <a href=\"https:\/\/vimeo.com\/intermedia\/videos\">nuestra p\u00e1gina<\/a> de vimeo \u00abAtados\u00bb, cortometraje dirigido por Paco Almazo y producido por Intermedia en 2009.\u00a0Premio RTVA a la Creaci\u00f3n Audiovisual Andaluza en el Festival de J\u00f3venes Realizadores de Granada.<\/div>\n<div>Esperamos que os guste.<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/intermediaproducciones.com\/en\/portfolio\/atados\/\">+info<\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div><iframe loading=\"lazy\" src=\"http:\/\/player.vimeo.com\/video\/41699562?title=0&amp;byline=0&amp;portrait=0\" frameborder=\"0\" width=\"500\" height=\"210\"><\/iframe><\/div>\n<div><\/div>","protected":false},"excerpt":{"rendered":"<p>Hemos subido a nuestra p\u00e1gina de vimeo \u00abAtados\u00bb, cortometraje dirigido por Paco Almazo y producido por Intermedia en 2009.\u00a0Premio RTVA a la Creaci\u00f3n Audiovisual Andaluza en el Festival de J\u00f3venes Realizadores de Granada. Esperamos que os guste. +info<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[75,76,24,74],"class_list":["post-954","post","type-post","status-publish","format-standard","hentry","category-eventos","tag-atados","tag-festival-de-jovenes-realizadores-de-granada","tag-intermedia-producciones","tag-paco-almazo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El cortometraje &quot;Atados&quot;, de Paco Almazo, completo en vimeo - Intermedia Producciones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intermediaproducciones.com\/en\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El cortometraje &quot;Atados&quot;, de Paco Almazo, completo en vimeo - Intermedia Producciones\" \/>\n<meta property=\"og:description\" content=\"Hemos subido a nuestra p\u00e1gina de vimeo \u00abAtados\u00bb, cortometraje dirigido por Paco Almazo y producido por Intermedia en 2009.\u00a0Premio RTVA a la Creaci\u00f3n Audiovisual Andaluza en el Festival de J\u00f3venes Realizadores de Granada. Esperamos que os guste. +info\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intermediaproducciones.com\/en\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/\" \/>\n<meta property=\"og:site_name\" content=\"Intermedia Producciones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ProductoraIntermediaProducciones\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-23T09:32:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-05-23T09:52:17+00:00\" \/>\n<meta name=\"author\" content=\"Intermedia Producciones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Intermedia Producciones\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/\"},\"author\":{\"name\":\"Intermedia Producciones\",\"@id\":\"https:\/\/intermediaproducciones.com\/#\/schema\/person\/7a7d709e77f232e65f14762c0719bb0b\"},\"headline\":\"El cortometraje \u00abAtados\u00bb, de Paco Almazo, completo en vimeo\",\"datePublished\":\"2012-05-23T09:32:52+00:00\",\"dateModified\":\"2012-05-23T09:52:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/\"},\"wordCount\":50,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/intermediaproducciones.com\/#organization\"},\"keywords\":[\"Atados\",\"Festival de J\u00f3venes Realizadores de Granada\",\"intermedia producciones\",\"Paco Almazo\"],\"articleSection\":[\"Eventos\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/\",\"url\":\"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/\",\"name\":\"El cortometraje \\\"Atados\\\", de Paco Almazo, completo en vimeo - Intermedia Producciones\",\"isPartOf\":{\"@id\":\"https:\/\/intermediaproducciones.com\/#website\"},\"datePublished\":\"2012-05-23T09:32:52+00:00\",\"dateModified\":\"2012-05-23T09:52:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/intermediaproducciones.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El cortometraje \u00abAtados\u00bb, de Paco Almazo, completo en vimeo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intermediaproducciones.com\/#website\",\"url\":\"https:\/\/intermediaproducciones.com\/\",\"name\":\"Intermedia Producciones\",\"description\":\"Miradas, Visiones y Realidades\",\"publisher\":{\"@id\":\"https:\/\/intermediaproducciones.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intermediaproducciones.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intermediaproducciones.com\/#organization\",\"name\":\"Intermedia Producciones\",\"url\":\"https:\/\/intermediaproducciones.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/intermediaproducciones.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intermediaproducciones.com\/wp-content\/uploads\/2019\/02\/logo_intermedia.png\",\"contentUrl\":\"https:\/\/intermediaproducciones.com\/wp-content\/uploads\/2019\/02\/logo_intermedia.png\",\"width\":199,\"height\":216,\"caption\":\"Intermedia Producciones\"},\"image\":{\"@id\":\"https:\/\/intermediaproducciones.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ProductoraIntermediaProducciones\",\"https:\/\/vimeo.com\/intermedia\",\"https:\/\/www.youtube.com\/user\/IntermediaProd\",\"https:\/\/www.instagram.com\/intermediaproducciones\/\",\"https:\/\/www.linkedin.com\/company\/intermedia-producciones\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/intermediaproducciones.com\/#\/schema\/person\/7a7d709e77f232e65f14762c0719bb0b\",\"name\":\"Intermedia Producciones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/intermediaproducciones.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=blank&r=g\",\"caption\":\"Intermedia Producciones\"},\"url\":\"https:\/\/intermediaproducciones.com\/en\/author\/intermedia-producciones\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El cortometraje \"Atados\", de Paco Almazo, completo en vimeo - Intermedia Producciones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intermediaproducciones.com\/en\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/","og_locale":"en_GB","og_type":"article","og_title":"El cortometraje \"Atados\", de Paco Almazo, completo en vimeo - Intermedia Producciones","og_description":"Hemos subido a nuestra p\u00e1gina de vimeo \u00abAtados\u00bb, cortometraje dirigido por Paco Almazo y producido por Intermedia en 2009.\u00a0Premio RTVA a la Creaci\u00f3n Audiovisual Andaluza en el Festival de J\u00f3venes Realizadores de Granada. Esperamos que os guste. +info","og_url":"https:\/\/intermediaproducciones.com\/en\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/","og_site_name":"Intermedia Producciones","article_publisher":"https:\/\/www.facebook.com\/ProductoraIntermediaProducciones","article_published_time":"2012-05-23T09:32:52+00:00","article_modified_time":"2012-05-23T09:52:17+00:00","author":"Intermedia Producciones","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Intermedia Producciones"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/#article","isPartOf":{"@id":"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/"},"author":{"name":"Intermedia Producciones","@id":"https:\/\/intermediaproducciones.com\/#\/schema\/person\/7a7d709e77f232e65f14762c0719bb0b"},"headline":"El cortometraje \u00abAtados\u00bb, de Paco Almazo, completo en vimeo","datePublished":"2012-05-23T09:32:52+00:00","dateModified":"2012-05-23T09:52:17+00:00","mainEntityOfPage":{"@id":"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/"},"wordCount":50,"commentCount":0,"publisher":{"@id":"https:\/\/intermediaproducciones.com\/#organization"},"keywords":["Atados","Festival de J\u00f3venes Realizadores de Granada","intermedia producciones","Paco Almazo"],"articleSection":["Eventos"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/","url":"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/","name":"El cortometraje \"Atados\", de Paco Almazo, completo en vimeo - Intermedia Producciones","isPartOf":{"@id":"https:\/\/intermediaproducciones.com\/#website"},"datePublished":"2012-05-23T09:32:52+00:00","dateModified":"2012-05-23T09:52:17+00:00","breadcrumb":{"@id":"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/intermediaproducciones.com\/el-cortometraje-atados-de-paco-almazo-completo-en-vimeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/intermediaproducciones.com\/"},{"@type":"ListItem","position":2,"name":"El cortometraje \u00abAtados\u00bb, de Paco Almazo, completo en vimeo"}]},{"@type":"WebSite","@id":"https:\/\/intermediaproducciones.com\/#website","url":"https:\/\/intermediaproducciones.com\/","name":"Intermedia Producciones","description":"Miradas, Visiones y Realidades","publisher":{"@id":"https:\/\/intermediaproducciones.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intermediaproducciones.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/intermediaproducciones.com\/#organization","name":"Intermedia Producciones","url":"https:\/\/intermediaproducciones.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/intermediaproducciones.com\/#\/schema\/logo\/image\/","url":"https:\/\/intermediaproducciones.com\/wp-content\/uploads\/2019\/02\/logo_intermedia.png","contentUrl":"https:\/\/intermediaproducciones.com\/wp-content\/uploads\/2019\/02\/logo_intermedia.png","width":199,"height":216,"caption":"Intermedia Producciones"},"image":{"@id":"https:\/\/intermediaproducciones.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ProductoraIntermediaProducciones","https:\/\/vimeo.com\/intermedia","https:\/\/www.youtube.com\/user\/IntermediaProd","https:\/\/www.instagram.com\/intermediaproducciones\/","https:\/\/www.linkedin.com\/company\/intermedia-producciones\/"]},{"@type":"Person","@id":"https:\/\/intermediaproducciones.com\/#\/schema\/person\/7a7d709e77f232e65f14762c0719bb0b","name":"Intermedia Producciones","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/intermediaproducciones.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=blank&r=g","caption":"Intermedia Producciones"},"url":"https:\/\/intermediaproducciones.com\/en\/author\/intermedia-producciones\/"}]}},"_links":{"self":[{"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/posts\/954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/comments?post=954"}],"version-history":[{"count":9,"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/posts\/954\/revisions"}],"predecessor-version":[{"id":960,"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/posts\/954\/revisions\/960"}],"wp:attachment":[{"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/media?parent=954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/categories?post=954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intermediaproducciones.com\/en\/wp-json\/wp\/v2\/tags?post=954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}